{"id":7697,"date":"2022-06-01T15:29:40","date_gmt":"2022-06-01T13:29:40","guid":{"rendered":"https:\/\/bobobooks.de\/?post_type=product&#038;p=7697"},"modified":"2026-03-22T22:07:49","modified_gmt":"2026-03-22T21:07:49","slug":"lu-shang-xing-zhou-yi-ge-zhong-guo-ji-zhe-de-la-mei-du-pin-diao-cha","status":"publish","type":"product","link":"https:\/\/bobobooks.de\/de\/lu_shang_xing_zhou\/","title":{"rendered":"Land Rover: Die Drogenermittlungen eines chinesischen Journalisten in Lateinamerika"},"content":{"rendered":"<p>Um die Nachrichten vor Ort zu verfolgen, ist Liu Snapdragon in die Slums eingedrungen, um Drogendealer zu befragen, hat den Schwarzmarkt f\u00fcr Waffen mit einer versteckten Kamera besucht und ist zu Beerdigungsinstituten und Friedh\u00f6fen gereist, um nach einer Leiche zu suchen, die gerade beerdigt werden soll. Um das Risiko der Berichterstattung zu minimieren, rekrutiert er Informanten aus der Fremde, getarnt als Lehrer, Gesch\u00e4ftsleute und Geologen. Es ist eine Berufswahl und ein Weg zur Wahrheit.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u4e3a\u4e86\u8ffd\u8e2a\u65b0\u95fb\u73b0\u573a\uff0c\u5218\u9a81\u9a9e\u6f5c\u5165\u8d2b\u6c11\u7a9f\u91c7\u8bbf\u8fc7\u6bd2\u8d29\uff0c\u5e26\u7740\u9690\u5f62\u6444\u50cf\u5934\u6697\u8bbf\u8fc7\u67aa\u652f\u9ed1\u5e02\uff0c\u6d41\u8fde\u4e8e\u6ba1\u4eea\u9986\u548c\u5893\u5730\u53ea\u4e3a\u5bfb\u627e\u4e00\u5177\u5373\u5c06 [&hellip;]<\/p>\n","protected":false},"featured_media":24984,"template":"","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[132641,132886],"product_tag":[],"class_list":["post-7697","product","type-product","status-publish","has-post-thumbnail","product_cat-132641","product_cat-132886","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/7697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/7697\/revisions"}],"predecessor-version":[{"id":10927,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/7697\/revisions\/10927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media\/24984"}],"wp:attachment":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media?parent=7697"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_brand?post=7697"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_cat?post=7697"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_tag?post=7697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}