{"id":5917,"date":"2022-01-17T08:34:27","date_gmt":"2022-01-17T07:34:27","guid":{"rendered":"https:\/\/bobobooks.de\/?post_type=product&#038;p=5917"},"modified":"2026-03-22T21:53:42","modified_gmt":"2026-03-22T20:53:42","slug":"von-dadu-nach-shangdu","status":"publish","type":"product","link":"https:\/\/bobobooks.de\/de\/cong-da-du-dao-shang-du\/","title":{"rendered":"Von Dadu nach Shangdu"},"content":{"rendered":"<p>Diese Stra\u00dfe verband die historische Stadt Dadu (das heutige Peking) und die Perle der Pr\u00e4rie, Shangdu (das heutige Zhenglan Banner, Xilingol Liga, Innere Mongolei).<\/p>\n<p>Diese Stra\u00dfe ist seit 800 Jahren staubig, als der kaiserliche Festzug noch gro\u00df war, der Fluss klar, das Gras saftig und die Pferde im Galopp unterwegs. Heutzutage ist sie ein Meer von Ver\u00e4nderungen. Die Pracht von vor achthundert Jahren ist in den gew\u00f6hnlichen D\u00f6rfern und Bergen verborgen.<\/p>\n<p>Luo Xin, Professor an der Universit\u00e4t Peking und Experte f\u00fcr die Geschichte des chinesischen Mittelalters und die Geschichte der alten Grenzv\u00f6lker Chinas, brach im Alter von chinesischen Haaren vom Kindergarten in Peking auf und reiste auf der alten kaiserlichen Kutschenstra\u00dfe nach Norden, wobei er Longhutai, Juyongguan, das Heigong-Tal und Shaling durchquerte, seinen Rucksack trug, die sich \u00fcberschneidenden T\u00e4ler von Peking und Hebei zu Fu\u00df durchquerte und das Grasland der Inneren Mongolei betrat, durch Felder und T\u00e4ler wanderte, ohne die sengende Sonne, den sintflutartigen Regen, den staubigen Boden und die beschwerlichen Wege zu f\u00fcrchten, und die vierhundertf\u00fcnfzig Kilometer \u00fcber Berge und Fl\u00fcsse vom Kindergarten bis zum Mingde-Tor zur\u00fccklegte, um Shangdu zu erreichen und sich so seinen lang gehegten Wunsch vor f\u00fcnfzehn Jahren zu erf\u00fcllen. Nachdem er die 450 Kilometer \u00fcber Berge und Fl\u00fcsse vom Jiande-Tor bis zum Mingde-Tor zur\u00fcckgelegt hatte, kam er in Shangdu an und erf\u00fcllte sich damit seinen lang gehegten Wunsch von vor f\u00fcnfzehn Jahren.<\/p>\n<p>\"Kenne ich als jemand, der sich beruflich mit der chinesischen Geschichte besch\u00e4ftigt hat, das China, das ich studiere, wirklich? Das frage ich mich immer wieder.\"<\/p>\n<p>Die Erz\u00e4hlung des Autors ist ruhig und gem\u00e4chlich, voller klassischem Flair, nachdenklich stimmend und sch\u00f6n zu lesen. In der Erz\u00e4hlung des Autors verflechten sich Geschichte und Realit\u00e4t und bieten faszinierende Farben.<\/p>\n<p>Auf dieser Stra\u00dfe gibt es die Geschichte auf der einen und die Realit\u00e4t auf der anderen Seite. Auf der einen Seite stehen die Wechself\u00e4lle der Abdr\u00fccke in den fernen Geschichtsb\u00fcchern, auf der anderen Seite die Sorgen und Freuden des Lebens in den letzten Jahrzehnten.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u4e00\u5ea7\u5386\u53f2\u540d\u57ce\u5927\u90fd\uff08\u4eca\u5317\u4eac\uff09\u548c\u4e00\u9897\u8349\u539f\u660e\u73e0\u4e0a\u90fd\uff08\u4eca\u5185\u8499\u53e4\u9521\u6797\u90ed\u52d2\u76df\u6b63\u84dd\u65d7\uff09\uff0c\u7531\u8fd9\u6761\u8def\u76f8\u8fde\u3002 \u8fd9\u6761\u8def\u5c18\u5c01\u4e86\u516b\u767e\u5e74\uff0c [&hellip;]<\/p>\n","protected":false},"featured_media":24954,"template":"","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[132641,132731],"product_tag":[],"class_list":["post-5917","product","type-product","status-publish","has-post-thumbnail","product_cat-132641","product_cat-132731","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/5917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":4,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/5917\/revisions"}],"predecessor-version":[{"id":10947,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/5917\/revisions\/10947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media\/24954"}],"wp:attachment":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media?parent=5917"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_brand?post=5917"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_cat?post=5917"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_tag?post=5917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}