{"id":4160,"date":"2021-08-18T10:54:32","date_gmt":"2021-08-18T08:54:32","guid":{"rendered":"https:\/\/bobobooks.de\/?post_type=product&#038;p=4160"},"modified":"2026-07-27T08:46:14","modified_gmt":"2026-07-27T06:46:14","slug":"im-land-china-reisen-mit-dem-zug","status":"publish","type":"product","link":"https:\/\/bobobooks.de\/de\/zai-zhong-guo-da-di-shang\/","title":{"rendered":"Im Land China: Reisen mit dem Zug"},"content":{"rendered":"<p>Ein Klassiker von Paul Thoroux, dem \"Paten der modernen Reiseliteratur\".<\/p>\n<p>Thomas Cook Travelling Literary Award Gewinner<\/p>\n<p>Eine neue Aufzeichnung der bewegenden und legend\u00e4ren 80er Jahre aus der Sicht eines Ausl\u00e4nders<\/p>\n<p>1986 kam Paul Thoroux nach einer sechsj\u00e4hrigen Unterbrechung nach China.<\/p>\n<p>Er reiste in pulsierende St\u00e4dte wie Peking und Shanghai und kam auch an Grenzorte wie Langxiang in Heilongjiang und Turpan in Xinjiang. Er reiste in das Land China und unterhielt sich mit allen m\u00f6glichen Leuten, mit jungen Leuten, die in der englischen Ecke des Shanghaier Volksparks ihr gesprochenes Englisch \u00fcbten, mit Studenten, die in das Import- und Exportgesch\u00e4ft einsteigen wollten, und mit Intellektuellen, die gerade die Shoah erlebt hatten. ...... Er benutzte einen scharfen und humorvollen Ton, um seine Geschichten unterwegs auszuspucken, aber er benutzte auch eine ruhige und rationale Perspektive, um den Charakter des chinesischen Volkes zu analysieren und um zu entdecken das t\u00e4gliche Leben und die sich wandelnden Gedanken der Chinesen im Wandel der Zeit.<\/p>\n<p>Die 80er Jahre haben wir weit hinter uns gelassen, aber auch unser heutiger Schwung und unser Dilemma sind ein D\u00e9j\u00e0-vu.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u201c\u73b0\u4ee3\u65c5\u884c\u6587\u5b66\u6559\u7236\u201d\u4fdd\u7f57\u00b7\u7d22\u9c81\u7ecf\u5178\u4e4b\u4f5c \u6258\u9a6c\u65af\u00b7\u5e93\u514b\u65c5\u884c\u6587\u5b66\u5956\u83b7\u5956\u4f5c\u54c1 \u6fc0\u8361\u4f20\u5947\u768480\u5e74\u4ee3\uff0c\u8001\u5916\u89c6\u89d2\u7684\u5168\u65b0\u8bb0\u5f55 [&hellip;]<\/p>\n","protected":false},"featured_media":26225,"template":"","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[132641,132731],"product_tag":[],"class_list":["post-4160","product","type-product","status-publish","has-post-thumbnail","product_cat-132641","product_cat-132731","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/4160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/4160\/revisions"}],"predecessor-version":[{"id":11721,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/4160\/revisions\/11721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media\/26225"}],"wp:attachment":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media?parent=4160"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_brand?post=4160"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_cat?post=4160"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_tag?post=4160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}