{"id":3815,"date":"2021-08-05T18:05:47","date_gmt":"2021-08-05T16:05:47","guid":{"rendered":"https:\/\/bobobooks.de\/?post_type=product&#038;p=3815"},"modified":"2026-01-01T16:22:18","modified_gmt":"2026-01-01T15:22:18","slug":"%e7%be%8e%e7%ac%ac%e5%a5%87%e9%93%b6%e8%a1%8c%e5%85%b4%e8%a1%b0-%e7%ae%a1%e7%90%86%e6%95%99%e7%9a%87%e8%b4%a2%e5%af%8c%e7%9a%84%e9%93%b6%e8%a1%8c%e5%ae%b6","status":"publish","type":"product","link":"https:\/\/bobobooks.de\/de\/mei-qi-di-yin-hang-jia\/","title":{"rendered":"Der Aufstieg und Fall der Medici-Bank: Der Bankier, der den Reichtum des Papstes verwaltete"},"content":{"rendered":"<p>\u2605 Die Medicis, wie wurden sie wirklich reich? Das Renaissance-Museum der Finanzen<\/p>\n<p>\u2605 Ein monumentaler Klassiker der mittelalterlichen Wirtschaftsgeschichte, eine perfekte Kombination aus erstklassiger Gelehrsamkeit und sch\u00f6ner Schrift<\/p>\n<p>\u2605 Harvard's \"Trupp-Payne Prize for Outstanding Business Writing\", mit einem Vorwort von Lai Jiancheng.<\/p>\n<p>\u2605 360-Grad-Analyse der mittelalterlichen Bankengiganten, um die Funktionsweise der Gesetze der Finanzwelt zu verstehen<\/p>\n<p>\u2605 Eine ganz andere Webersche Geschichte des Kapitalismus und das Verst\u00e4ndnis der Urspr\u00fcnge des modernen Wirtschaftssystems<\/p>\n<p>\u2605 Jedes Zeitalter hat seinen eigenen Handel, und die menschliche Natur ist seit Jahrhunderten unver\u00e4ndert geblieben.<\/p>\n<p>.<\/p>\n<p>.<\/p>\n<p>Der moderne Kapitalismus hat seine Wurzeln im Italien des Mittelalters und der Renaissance. Von den Kreuzz\u00fcgen bis zu den geografischen Entdeckungen war Italien die dominierende Wirtschaftsmacht in der westlichen Welt. Die italienische Hegemonie beruhte auf einer ausgezeichneten Handelsorganisation. Die meisten der Handelssysteme der heutigen Marktwirtschaft sind italienische Erfindungen. Der sp\u00e4tmittelalterliche Finanzgigant, die Medici-Bank, ist eine Abk\u00fcrzung, um die Urspr\u00fcnge des modernen Handels zu verstehen, und ein grundlegendes Thema f\u00fcr das Verst\u00e4ndnis der Geschichte des westlichen Finanzwesens.<\/p>\n<p>.<\/p>\n<p>Die Medici-Bank war im 15. Jahrhundert die gr\u00f6\u00dfte Bank in Europa mit Hauptsitz in Florenz, Italien, und Zweigstellen in wichtigen St\u00e4dten Westeuropas. Die Medici-Bank war der Verm\u00f6gensverwalter der Kirche, vergab Kredite an F\u00fcrsten und Adlige und f\u00f6rderte den internationalen Handel in Westeuropa. Die Medici unterst\u00fctzten in hohem Ma\u00dfe literarische und k\u00fcnstlerische Aktivit\u00e4ten und spielten eine zentrale Rolle bei der F\u00f6rderung der Renaissance. Die Medici-Bank stellte die h\u00f6chste Errungenschaft des Handelssystems in der Anfangszeit des Kapitalismus dar: Sie entwarf eine Organisationsform, die der einer Holding \u00e4hnelte, und fand einen Weg, multinationale Konzerne aus der Ferne zu kontrollieren; sie manipulierte die Preise mit ihren Konkurrenten auf dem Alaunmarkt und gr\u00fcndete das fr\u00fcheste Kartell in der Geschichte der Menschheit; sie \u00fcbernahm und verbreitete die Methode der doppelten Buchf\u00fchrung, die es von nun an erm\u00f6glichte, die Gr\u00f6\u00dfe des Kapitals quantitativ zu erfassen, und legte den Grundstein f\u00fcr das Entstehen des Kapitalismus. Sie legte den Grundstein f\u00fcr die Entstehung des Kapitalismus.<\/p>\n<p>.<\/p>\n<p>Ein gro\u00dfer Teil der B\u00fccher, Aufzeichnungen und Korrespondenz der Medici-Bank ist bis heute erhalten geblieben. Dieses Buch nutzt diese wertvollen historischen Materialien, um den institutionellen Hintergrund, das Gesch\u00e4ftsmodell und die Organisationsstruktur der Medici zu beschreiben. Die Pers\u00f6nlichkeitsfaktoren der Partner und Manager, die Finanzzahlen der Gesch\u00e4ftsvorg\u00e4nge und die Gewinnbeteiligung werden in die Geschichte vom Aufstieg und Fall des Jahrhunderts einbezogen. Sie k\u00f6nnen ein Gruppenportr\u00e4t der aufeinanderfolgenden Medici-Inhaber sehen, die faszinierende Geschichte der Verflechtung von Wirtschaft, Politik und Religion lesen und einen Einblick in die sich ver\u00e4ndernde politische und wirtschaftliche Situation in den L\u00e4ndern Westeuropas gewinnen.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u2605 \u7f8e\u7b2c\u5947\u5bb6\u65cf\uff0c\u5230\u5e95\u662f\u600e\u4e48\u53d1\u5bb6\u7684\uff1f\u6587\u827a\u590d\u5174\u7684\u91d1\u878d\u535a\u7269\u9986 \u2605 \u4e2d\u4e16\u7eaa\u7ecf\u6d4e\u53f2\u4e0d\u673d\u7ecf\u5178\uff0c\u4e00\u6d41\u5b66\u672f\u4e0e\u4f18\u7f8e\u6587\u5b57\u7684\u5b8c\u7f8e\u7ed3\u5408 [&hellip;]<\/p>\n","protected":false},"featured_media":26227,"template":"","meta":{"_acf_changed":false,"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":""},"product_brand":[],"product_cat":[132633,132900],"product_tag":[],"class_list":["post-3815","product","type-product","status-publish","has-post-thumbnail","product_cat-132633","product_cat-132900","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"exclude_global_add_ons":[],"addons":[],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/3815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":2,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/3815\/revisions"}],"predecessor-version":[{"id":11905,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product\/3815\/revisions\/11905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media\/26227"}],"wp:attachment":[{"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/media?parent=3815"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_brand?post=3815"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_cat?post=3815"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bobobooks.de\/de\/wp-json\/wp\/v2\/product_tag?post=3815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}